{"id":41694,"date":"2021-03-01T14:53:06","date_gmt":"2021-03-01T13:53:06","guid":{"rendered":"https:\/\/mms-seminar.com\/het-universele-tegengif\/"},"modified":"2023-02-11T13:13:51","modified_gmt":"2023-02-11T12:13:51","slug":"het-universele-tegengif","status":"publish","type":"post","link":"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/","title":{"rendered":"&#8220;Het universele tegengif.&#8221;"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"41694\" class=\"elementor elementor-41694 elementor-41634\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-113971b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"113971b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-af4490e\" data-id=\"af4490e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd69b66 elementor-widget elementor-widget-text-editor\" data-id=\"cd69b66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Deze documentaire gaat over de werkzame stof chloordioxide, een krachtige antivirale en antibacteri\u00eble stof die wordt gebruikt voor de behandeling van allerlei ziektekiemen. Deze documentaire gaat dieper in op de wetenschap achter CDS en verkent deze aan de hand van voorbeelden. Bekijk nu de Duitse nasynchronisatie:<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ef13f5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ef13f5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9dd05b8\" data-id=\"9dd05b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b8845e elementor-widget elementor-widget-video\" data-id=\"5b8845e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe\" allowfullscreen allow=\"clipboard-write\" title=\"vimeo videospeler\" src=\"https:\/\/player.vimeo.com\/video\/797269128?color&amp;autopause=0&amp;loop=0&amp;muted=0&amp;title=1&amp;portrait=1&amp;byline=1#t=\"><\/iframe>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f8aff6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f8aff6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0434fe2\" data-id=\"0434fe2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7987d69 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7987d69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2023\/02\/The-Universal-Antidote-Interactive-Reference-Guidebook.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-file-download\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">The Universal Antidote Interactive Reference Guidebook<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ba315f3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ba315f3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-584474c\" data-id=\"584474c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-77c4dbdf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"77c4dbdf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-a8a5248\" data-id=\"a8a5248\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ddaa813 elementor-widget elementor-widget-spacer\" data-id=\"7ddaa813\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49cb7a66 elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"49cb7a66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/aquarius-prolife.com\/de\/23-chlordioxid-produkte\" target=\"_blank\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"400\" src=\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2022\/11\/Banner_quer_cdspure.jpg\" class=\"attachment-full size-full wp-image-47131\" alt=\"\" srcset=\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2022\/11\/Banner_quer_cdspure.jpg 1200w, https:\/\/mms-seminar.com\/wp-content\/uploads\/2022\/11\/Banner_quer_cdspure-300x100.jpg 300w, https:\/\/mms-seminar.com\/wp-content\/uploads\/2022\/11\/Banner_quer_cdspure-1024x341.jpg 1024w, https:\/\/mms-seminar.com\/wp-content\/uploads\/2022\/11\/Banner_quer_cdspure-768x256.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7611c36a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7611c36a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-64685b8c\" data-id=\"64685b8c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2083d418 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"2083d418\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/aquarius-prolife.com\/de\/23-chlordioxid-produkte\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"250\" src=\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2022\/11\/Banner_mobile_cdspure.gif\" class=\"attachment-full size-full wp-image-47123\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ca2d004 elementor-widget elementor-widget-spacer\" data-id=\"3ca2d004\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-693dddf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"693dddf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f1a4224\" data-id=\"f1a4224\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2288297 elementor-widget elementor-widget-html\" data-id=\"2288297\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe id=\"lbry-iframe\" width=\"560\" height=\"315\" src=\"https:\/\/odysee.com\/%24\/embed\/The-Universal-Antidote-spainish-subtitles\/28fc857e11e1e730c4625a7a8b9ba1d04bf172ee?r=HEm8VaMSNbMfYogyRuMuk5GBVptgJvYn\" allowfullscreen=\"\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1590f3a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1590f3a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-30acb4d\" data-id=\"30acb4d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53a614e elementor-widget elementor-widget-text-editor\" data-id=\"53a614e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In een internationale documentatie worden de vele successen en mogelijke toepassingen van de werkzame stof chloordioxide opgesomd. Deze documentaire is in het Engels met Spaanse ondertitels.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d91467e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d91467e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f7cf1c5\" data-id=\"f7cf1c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55d5dcf elementor-widget elementor-widget-video\" data-id=\"55d5dcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe\" allowfullscreen allow=\"clipboard-write\" title=\"vimeo videospeler\" src=\"https:\/\/player.vimeo.com\/video\/512167428?color&amp;autopause=0&amp;loop=0&amp;muted=0&amp;title=1&amp;portrait=1&amp;byline=1#t=\"><\/iframe>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ddc919 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ddc919\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4874aee\" data-id=\"4874aee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e79da98 elementor-widget elementor-widget-text-editor\" data-id=\"e79da98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In deze video interviewt Truther Jordan Sather, die zeer bekend is in de VS, Andreas Kalcker over de huidige covidale successen van chloordioxide en de internationale documentaire &#8220;The Universal Antidote&#8221;. (Engels)<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-145f3b5d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"145f3b5d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4439db15\" data-id=\"4439db15\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4a632bba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4a632bba\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-11aa86bf\" data-id=\"11aa86bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ec496c7 elementor-widget elementor-widget-spacer\" data-id=\"2ec496c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f418030 elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"1f418030\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ticketshop.akasha-congress.com.\/s\/AKASHA-Congress?group_id=816\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1200\" height=\"400\" src=\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/Banner_quer_videobundle.jpg\" class=\"attachment-full size-full wp-image-37673\" alt=\"\" srcset=\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/Banner_quer_videobundle.jpg 1200w, https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/Banner_quer_videobundle-300x100.jpg 300w, https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/Banner_quer_videobundle-1024x341.jpg 1024w, https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/Banner_quer_videobundle-768x256.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-24542507 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"24542507\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-75618670\" data-id=\"75618670\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25d814e6 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"25d814e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ticketshop.akasha-congress.com.\/s\/AKASHA-Congress?group_id=816\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"250\" src=\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2017\/09\/banner-photoshop-DVD-Set.gif\" class=\"attachment-full size-full wp-image-37693\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b8a443c elementor-widget elementor-widget-spacer\" data-id=\"1b8a443c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Deze documentaire gaat over de werkzame stof chloordioxide, een krachtige antivirale en antibacteri\u00eble stof die wordt gebruikt voor de behandeling van allerlei ziektekiemen. Deze documentaire gaat dieper in op de wetenschap achter CDS en verkent deze aan [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":41647,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1027,1262],"tags":[],"class_list":["post-41694","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geen-onderdeel-van-een-categorie","category-mms-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>&quot;Het universele tegengif&quot; - Chloordioxide<\/title>\n<meta name=\"description\" content=\"Documentatie met de werkzame stof chloordioxide, sterke antivirale en antibacteri\u00eble stof voor de behandeling van ziektekiemen. Zie meer in de video.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Het universele tegengif.&quot;\" \/>\n<meta property=\"og:description\" content=\"Documentatie met de werkzame stof chloordioxide, sterke antivirale en antibacteri\u00eble stof voor de behandeling van ziektekiemen. Zie meer in de video.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/\" \/>\n<meta property=\"og:site_name\" content=\"MMS Seminar | Chlordioxid (CDS\/CDL) nach Jim Humble &amp; A. Kalcker\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MMSseminare\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-01T13:53:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-11T12:13:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2021\/02\/Bildschirmfoto-2021-02-14-um-14.24.07.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1850\" \/>\n\t<meta property=\"og:image:height\" content=\"1032\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Teamer MMSler\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"Teamer MMSler\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/\"},\"author\":{\"name\":\"Teamer MMSler\",\"@id\":\"https:\/\/mms-seminar.com\/nl\/#\/schema\/person\/12cfbf6bc9c92529d726b3c9281772bd\"},\"headline\":\"&#8220;Het universele tegengif.&#8221;\",\"datePublished\":\"2021-03-01T13:53:06+00:00\",\"dateModified\":\"2023-02-11T12:13:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/\"},\"wordCount\":119,\"publisher\":{\"@id\":\"https:\/\/mms-seminar.com\/nl\/#organization\"},\"image\":{\"@id\":\"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2021\/02\/Bildschirmfoto-2021-02-14-um-14.24.07.jpg\",\"articleSection\":[\"Geen onderdeel van een categorie\",\"MMS-Blog\"],\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/\",\"url\":\"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/\",\"name\":\"\\\"Het universele tegengif\\\" - Chloordioxide\",\"isPartOf\":{\"@id\":\"https:\/\/mms-seminar.com\/nl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2021\/02\/Bildschirmfoto-2021-02-14-um-14.24.07.jpg\",\"datePublished\":\"2021-03-01T13:53:06+00:00\",\"dateModified\":\"2023-02-11T12:13:51+00:00\",\"description\":\"Documentatie met de werkzame stof chloordioxide, sterke antivirale en antibacteri\u00eble stof voor de behandeling van ziektekiemen. Zie meer in de video.\",\"breadcrumb\":{\"@id\":\"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/#primaryimage\",\"url\":\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2021\/02\/Bildschirmfoto-2021-02-14-um-14.24.07.jpg\",\"contentUrl\":\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2021\/02\/Bildschirmfoto-2021-02-14-um-14.24.07.jpg\",\"width\":1850,\"height\":1032},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mms-seminar.com\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Het universele tegengif.&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mms-seminar.com\/nl\/#website\",\"url\":\"https:\/\/mms-seminar.com\/nl\/\",\"name\":\"MMS Seminar | Chlordioxid (CDS\/CDL) nach Jim Humble & A. Kalcker\",\"description\":\"Dein Wissensportal zu MMS, CDS\/CDL &amp; Methylenblau nach Jim Humble und Andreas Kalcker.\",\"publisher\":{\"@id\":\"https:\/\/mms-seminar.com\/nl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mms-seminar.com\/nl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mms-seminar.com\/nl\/#organization\",\"name\":\"MMS-Seminar\",\"url\":\"https:\/\/mms-seminar.com\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/mms-seminar.com\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2017\/08\/cropped-mms-logo-weiss-560x80-2.png\",\"contentUrl\":\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2017\/08\/cropped-mms-logo-weiss-560x80-2.png\",\"width\":446,\"height\":80,\"caption\":\"MMS-Seminar\"},\"image\":{\"@id\":\"https:\/\/mms-seminar.com\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/MMSseminare\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/mms-seminar.com\/nl\/#\/schema\/person\/12cfbf6bc9c92529d726b3c9281772bd\",\"name\":\"Teamer MMSler\",\"url\":\"https:\/\/mms-seminar.com\/nl\/author\/mms-dreamteam2016-2-2-2-2-2-2\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\"Het universele tegengif\" - Chloordioxide","description":"Documentatie met de werkzame stof chloordioxide, sterke antivirale en antibacteri\u00eble stof voor de behandeling van ziektekiemen. Zie meer in de video.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/","og_locale":"nl_NL","og_type":"article","og_title":"\"Het universele tegengif.\"","og_description":"Documentatie met de werkzame stof chloordioxide, sterke antivirale en antibacteri\u00eble stof voor de behandeling van ziektekiemen. Zie meer in de video.","og_url":"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/","og_site_name":"MMS Seminar | Chlordioxid (CDS\/CDL) nach Jim Humble &amp; A. Kalcker","article_publisher":"https:\/\/www.facebook.com\/MMSseminare","article_published_time":"2021-03-01T13:53:06+00:00","article_modified_time":"2023-02-11T12:13:51+00:00","og_image":[{"width":1850,"height":1032,"url":"https:\/\/mms-seminar.com\/wp-content\/uploads\/2021\/02\/Bildschirmfoto-2021-02-14-um-14.24.07.jpg","type":"image\/jpeg"}],"author":"Teamer MMSler","twitter_misc":{"Geschreven door":"Teamer MMSler","Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/#article","isPartOf":{"@id":"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/"},"author":{"name":"Teamer MMSler","@id":"https:\/\/mms-seminar.com\/nl\/#\/schema\/person\/12cfbf6bc9c92529d726b3c9281772bd"},"headline":"&#8220;Het universele tegengif.&#8221;","datePublished":"2021-03-01T13:53:06+00:00","dateModified":"2023-02-11T12:13:51+00:00","mainEntityOfPage":{"@id":"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/"},"wordCount":119,"publisher":{"@id":"https:\/\/mms-seminar.com\/nl\/#organization"},"image":{"@id":"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/#primaryimage"},"thumbnailUrl":"https:\/\/mms-seminar.com\/wp-content\/uploads\/2021\/02\/Bildschirmfoto-2021-02-14-um-14.24.07.jpg","articleSection":["Geen onderdeel van een categorie","MMS-Blog"],"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/","url":"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/","name":"\"Het universele tegengif\" - Chloordioxide","isPartOf":{"@id":"https:\/\/mms-seminar.com\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/#primaryimage"},"image":{"@id":"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/#primaryimage"},"thumbnailUrl":"https:\/\/mms-seminar.com\/wp-content\/uploads\/2021\/02\/Bildschirmfoto-2021-02-14-um-14.24.07.jpg","datePublished":"2021-03-01T13:53:06+00:00","dateModified":"2023-02-11T12:13:51+00:00","description":"Documentatie met de werkzame stof chloordioxide, sterke antivirale en antibacteri\u00eble stof voor de behandeling van ziektekiemen. Zie meer in de video.","breadcrumb":{"@id":"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/#primaryimage","url":"https:\/\/mms-seminar.com\/wp-content\/uploads\/2021\/02\/Bildschirmfoto-2021-02-14-um-14.24.07.jpg","contentUrl":"https:\/\/mms-seminar.com\/wp-content\/uploads\/2021\/02\/Bildschirmfoto-2021-02-14-um-14.24.07.jpg","width":1850,"height":1032},{"@type":"BreadcrumbList","@id":"https:\/\/mms-seminar.com\/nl\/het-universele-tegengif\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mms-seminar.com\/nl\/"},{"@type":"ListItem","position":2,"name":"&#8220;Het universele tegengif.&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/mms-seminar.com\/nl\/#website","url":"https:\/\/mms-seminar.com\/nl\/","name":"MMS Seminar | Chlordioxid (CDS\/CDL) nach Jim Humble & A. Kalcker","description":"Dein Wissensportal zu MMS, CDS\/CDL &amp; Methylenblau nach Jim Humble und Andreas Kalcker.","publisher":{"@id":"https:\/\/mms-seminar.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mms-seminar.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/mms-seminar.com\/nl\/#organization","name":"MMS-Seminar","url":"https:\/\/mms-seminar.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/mms-seminar.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/mms-seminar.com\/wp-content\/uploads\/2017\/08\/cropped-mms-logo-weiss-560x80-2.png","contentUrl":"https:\/\/mms-seminar.com\/wp-content\/uploads\/2017\/08\/cropped-mms-logo-weiss-560x80-2.png","width":446,"height":80,"caption":"MMS-Seminar"},"image":{"@id":"https:\/\/mms-seminar.com\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MMSseminare"]},{"@type":"Person","@id":"https:\/\/mms-seminar.com\/nl\/#\/schema\/person\/12cfbf6bc9c92529d726b3c9281772bd","name":"Teamer MMSler","url":"https:\/\/mms-seminar.com\/nl\/author\/mms-dreamteam2016-2-2-2-2-2-2\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/mms-seminar.com\/wp-content\/uploads\/2021\/02\/Bildschirmfoto-2021-02-14-um-14.24.07.jpg",1850,1032,false],"thumbnail":["https:\/\/mms-seminar.com\/wp-content\/uploads\/2021\/02\/Bildschirmfoto-2021-02-14-um-14.24.07-150x150.jpg",150,150,true],"medium":["https:\/\/mms-seminar.com\/wp-content\/uploads\/2021\/02\/Bildschirmfoto-2021-02-14-um-14.24.07-300x167.jpg",300,167,true],"medium_large":["https:\/\/mms-seminar.com\/wp-content\/uploads\/2021\/02\/Bildschirmfoto-2021-02-14-um-14.24.07-768x428.jpg",768,428,true],"large":["https:\/\/mms-seminar.com\/wp-content\/uploads\/2021\/02\/Bildschirmfoto-2021-02-14-um-14.24.07-1024x571.jpg",1024,571,true],"1536x1536":["https:\/\/mms-seminar.com\/wp-content\/uploads\/2021\/02\/Bildschirmfoto-2021-02-14-um-14.24.07-1536x857.jpg",1536,857,true],"2048x2048":["https:\/\/mms-seminar.com\/wp-content\/uploads\/2021\/02\/Bildschirmfoto-2021-02-14-um-14.24.07.jpg",1850,1032,false]},"uagb_author_info":{"display_name":"Teamer MMSler","author_link":"https:\/\/mms-seminar.com\/nl\/author\/mms-dreamteam2016-2-2-2-2-2-2\/"},"uagb_comment_info":0,"uagb_excerpt":"Deze documentaire gaat over de werkzame stof chloordioxide, een krachtige antivirale en antibacteri\u00eble stof die wordt gebruikt voor de behandeling van allerlei ziektekiemen. Deze documentaire gaat dieper in op de wetenschap achter CDS en verkent deze aan [&hellip;]","_links":{"self":[{"href":"https:\/\/mms-seminar.com\/nl\/wp-json\/wp\/v2\/posts\/41694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mms-seminar.com\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mms-seminar.com\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mms-seminar.com\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mms-seminar.com\/nl\/wp-json\/wp\/v2\/comments?post=41694"}],"version-history":[{"count":0,"href":"https:\/\/mms-seminar.com\/nl\/wp-json\/wp\/v2\/posts\/41694\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mms-seminar.com\/nl\/wp-json\/wp\/v2\/media\/41647"}],"wp:attachment":[{"href":"https:\/\/mms-seminar.com\/nl\/wp-json\/wp\/v2\/media?parent=41694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mms-seminar.com\/nl\/wp-json\/wp\/v2\/categories?post=41694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mms-seminar.com\/nl\/wp-json\/wp\/v2\/tags?post=41694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}