{"id":37173,"date":"2020-12-30T15:31:53","date_gmt":"2020-12-30T14:31:53","guid":{"rendered":"https:\/\/mms-seminar.com\/incurabile-era-ieri\/"},"modified":"2023-02-27T12:08:09","modified_gmt":"2023-02-27T11:08:09","slug":"incurabile-era-ieri","status":"publish","type":"post","link":"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/","title":{"rendered":"Incurabile era ieri!"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"37173\" class=\"elementor elementor-37173 elementor-3629\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b7c66d2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b7c66d2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1d1a943\" data-id=\"1d1a943\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d2dad7f elementor-widget elementor-widget-text-editor\" data-id=\"3d2dad7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong style=\"font-size: 16px;\">Dal veterinario di Amburgo Dirk Schrader: &#8220;\u00c8 il destino toccante di diversi cani e di un puledro che mi fa pensare se l&#8217;insegnamento delle infezioni in medicina veterinaria debba essere riscritto. Somministrare una sostanza di mia produzione, il cui nome non mi \u00e8 ancora permesso nominare pubblicamente a causa dell&#8217;attuale situazione giuridica, potrebbe salvare questi animali dall&#8217;infermit\u00e0 e dalla morte. Il costo? La sostanza costa meno del suo imballaggio ed \u00e8 facile da produrre da soli.<\/strong><\/p>\n<h3>Caso 1: Poliartrite<\/h3>\n<p>Il quasi 1 \u00bd &#8211; anno Cairn terrier della famiglia H. non poteva camminare da un giorno all&#8217;altro: Era zoppo davanti, poi dietro. Una schiena storta e un dolore chiaramente crescente hanno allarmato i proprietari degli animali. Sono andati in una rinomata struttura veterinaria vicino ad Amburgo. TAC, risonanza magnetica, gli esami del sangue sono risultati negativi. Solo i valori dei leucociti erano significativamente elevati, i farmaci antinfiammatori e gli antibiotici non hanno funzionato. I proprietari di animali domestici, innervositi, mi hanno raccontato della loro impotenza e del continuo e grave disturbo del loro cagnolino. I veterinari avevano pronunciato la parola &#8220;poliartrite&#8221; e tolto <strong>qualsiasi speranza<\/strong> alla famiglia. Al cagnolino veniva somministrato il suddetto rimedio per via orale due volte al giorno. Dopo tre giorni correva di nuovo felicemente per il giardino. Il periodo di trattamento di 14 giorni in totale \u00e8 stato rispettato. Il risultato: un cane sano, una famiglia felice e &#8211; valori leucocitari normali.<\/p>\n<h3>Caso 2: Infezione da tetano<\/h3>\n<p>Il grande maschio Malinois della famiglia S. ha mostrato tutti i segni di un&#8217;infezione tetanica avanzata. <strong>Incurabile secondo la dottrina<\/strong>. Purtroppo. La signora S. ha trattato il suo cane tre volte al giorno con la sostanza di cui sopra. Dopo 10 giorni era chiaro: il cane poteva continuare a vivere. L&#8217;agente patogeno del tetano Chlostridium tetani \u00e8 stato probabilmente fermato molto rapidamente con i soliti antibiotici. La sua tossina da sola ha devastato le cellule nervose e le sinapsi &#8211; inaccessibile anche al siero del tetano. La terapia autoprodotta ha dimostrato che la tossina tetanica pu\u00f2 essere distrutta dalla sostanza autoprodotta. La famiglia S. ha di nuovo il suo cane vitale e sano.<\/p>\n<h3>Caso 3: zoppia del puledro<\/h3>\n<p>Il 30.5.2015 Venere ha dato alla luce Bado, il suo secondo puledro. Ma non poteva alzarsi a bere da sua madre. I veterinari che sono stati chiamati si sono iniettati tutto quello che la loro farmacia aveva da offrire &#8211; per tre settimane. Le articolazioni di Bado si sono gonfiate, una visione di miseria, nessun miglioramento. All&#8217;ultimo trattamento il veterinario ha detto che non poteva aiutare. Domani vuole mettere a dormire Bado. Il proprietario dovrebbe gi\u00e0 chiamare il knacker. Bado deve avere una zoppia di puledro, dopo tutto. <strong>La malattia \u00e8 incurabile<\/strong>. La coraggiosa signora S. aveva sentito parlare del caso di tetano (vedi sopra) e decise di trattare Bado con la suddetta sostanza tre volte al giorno. La dose \u00e8 stata presa x 4. Dopo tre giorni Bado si \u00e8 alzato, ancora zoppo, ma i giorni successivi ha mostrato un rapido miglioramento delle sue condizioni. Dopo una settimana Bado correva felicemente dietro alla madre, un puledro sano e vitale. Una sensazione per gli amanti dei cavalli nel Vierlanden.<\/p>\n<h3>Caso 4: Infezione da MRSA durante l&#8217;intervento chirurgico<\/h3>\n<p>Chiamata da Hannover. Volevano sapere quanto sarebbe costato amputare una zampa posteriore su una miscela tedesca Shepherd. Non da 800 a 1000 euro? No. La met\u00e0 al massimo, vedo. Franjo, quattro anni, aveva probabilmente contratto un&#8217;infezione multifarmacoresistente durante un intervento al legamento crociato. Dopo trattamenti antibiotici infruttuosi, la <strong>facolt\u00e0 di veterinaria di Hannover consigli\u00f2 l&#8217;<\/strong> <strong>amputazione<\/strong>. I proprietari non hanno potuto raccogliere i soldi.<br \/>\nhttps:\/\/www.youtube.com\/watch?v=y9td-3HW5Hg<\/p>\n<p>Franjo \u00e8 stato ricoverato in ospedale con noi e l&#8217;articolazione infetta \u00e8 stata &#8220;pompata&#8221; tre volte al giorno con la suddetta sostanza. Inoltre, anche questo gli veniva dato tre volte al giorno. Dopo una settimana Franjo non ha pi\u00f9 sofferto. Dopo un&#8217;altra settimana, siamo stati in grado di tirare il tubo nell&#8217;articolazione del ginocchio. L&#8217;osteomielite al ginocchio \u00e8 stata eliminata. Oggi vive senza zoppia e come un cane felice con la sua famiglia.<\/p>\n<p><a href=\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2015\/06\/DirkSchrader.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft wp-image-3557 size-full\" src=\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2015\/06\/DirkSchrader.jpg\" alt=\"DirkSchrader\" width=\"282\" height=\"304\" srcset=\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2015\/06\/DirkSchrader.jpg 282w, https:\/\/mms-seminar.com\/wp-content\/uploads\/2015\/06\/DirkSchrader-278x300.jpg 278w\" sizes=\"(max-width: 282px) 100vw, 282px\" \/><\/a>Questi quattro esempi, cos\u00ec come decine di altri, dimostrano che l&#8217;uso della suddetta sostanza offre un&#8217;enorme opportunit\u00e0 per contrastare efficacemente le infezioni in modo giusto. Continueremo a dare agli animali infetti la possibilit\u00e0 di continuare a vivere senza preoccupazioni. Tuttavia, un&#8217;autorit\u00e0 di Amburgo ci ha proibito di produrre noi stessi la sostanza deliberata e di usarla sugli animali. Che si tratti della &#8220;mostruosa stupidit\u00e0 dei tedeschi&#8221; citata da Schopenhauer, o di quella che Hannah Arendt chiama &#8220;la banalit\u00e0 del male&#8221;, un giorno potremo sentire dai giudici di Amburgo se ci sar\u00e0 permesso di usare la sostanza cos\u00ec beneficamente impiegata senza essere perseguiti da questa autorit\u00e0, e perch\u00e9. Siamo fiduciosi e confidiamo nel sano senso della giustizia. Amburgo, luglio 2015&#8243;<\/p>\n<p>Questo \u00e8 il testo completo di una e-mail da <strong>veterinario Dirk Schrader<\/strong> al nostro team.<br \/>\n<em><br \/>\nIstituto veterinario<br \/>\nper la medicina applicata ai piccoli animali<br \/>\nVia Rahlstedter 156<br \/>\n22143 Amburgo<br \/>\nTel. 0049-40-677 21 44<\/em><br \/>\n<a href=\"http:\/\/www.tieraerzte-hamburg.com\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.tieraerzte-hamburg.com<\/a><\/p>\n<h4>Commento dell&#8217;editore:<\/h4>\n<p>Questo agente minaccioso pu\u00f2 essere parafrasato come segue:<\/p>\n<p><strong>M<\/strong>anche <strong>M<\/strong>oegen <strong>S<\/strong>\u00fcss<br \/>\n<strong>M<\/strong>anche <strong>M<\/strong>it <strong>S<\/strong>auer<br \/>\n<strong>M<\/strong>anche <strong>M<\/strong>oegen <strong>S<\/strong>sharp<br \/>\n<strong>M<\/strong>ulti-<strong>M<\/strong>ottanta <strong>S<\/strong>soup<br \/>\n&#8230;&#8230; o avete un&#8217;altra parafrasi migliore?<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7464ad60 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7464ad60\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6e08de88\" data-id=\"6e08de88\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2f906a46 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f906a46\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3dd25c34\" data-id=\"3dd25c34\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-607448f6 elementor-widget elementor-widget-spacer\" data-id=\"607448f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43a2f1dd elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"43a2f1dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/aquarius-prolife.com\/de\/28-classic-set\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1200\" height=\"400\" src=\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/Banner_quer_mmsclassic.jpg\" class=\"attachment-full size-full wp-image-35063\" alt=\"\" srcset=\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/Banner_quer_mmsclassic.jpg 1200w, https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/Banner_quer_mmsclassic-300x100.jpg 300w, https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/Banner_quer_mmsclassic-1024x341.jpg 1024w, https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/Banner_quer_mmsclassic-768x256.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-67de56d1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"67de56d1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4d34662d\" data-id=\"4d34662d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-440a213c elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"440a213c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/aquarius-prolife.com\/de\/28-classic-set\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"250\" src=\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/06\/Banner_mobile_mms.gif\" class=\"attachment-full size-full wp-image-35067\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75fda6d7 elementor-widget elementor-widget-spacer\" data-id=\"75fda6d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Dal veterinario di Amburgo Dirk Schrader: &#8220;\u00c8 il destino toccante di diversi cani e di un puledro che mi fa pensare se l&#8217;insegnamento delle infezioni in medicina veterinaria debba essere riscritto. Somministrare una sostanza di mia produzione, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":37014,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1262,1026],"tags":[],"class_list":["post-37173","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mms-blog","category-non-categorizzato"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Incurabile era ieri! - MMS Seminar | Chlordioxid (CDS\/CDL) nach Jim Humble &amp; A. Kalcker<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Incurabile era ieri!\" \/>\n<meta property=\"og:description\" content=\"Dal veterinario di Amburgo Dirk Schrader: &#8220;\u00c8 il destino toccante di diversi cani e di un puledro che mi fa pensare se l&#8217;insegnamento delle infezioni in medicina veterinaria debba essere riscritto. Somministrare una sostanza di mia produzione, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/\" \/>\n<meta property=\"og:site_name\" content=\"MMS Seminar | Chlordioxid (CDS\/CDL) nach Jim Humble &amp; A. Kalcker\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MMSseminare\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-30T14:31:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-27T11:08:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2015\/06\/DirkSchrader.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"282\" \/>\n\t<meta property=\"og:image:height\" content=\"304\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Teamer MMSler\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Teamer MMSler\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/\"},\"author\":{\"name\":\"Teamer MMSler\",\"@id\":\"https:\/\/mms-seminar.com\/it\/#\/schema\/person\/12cfbf6bc9c92529d726b3c9281772bd\"},\"headline\":\"Incurabile era ieri!\",\"datePublished\":\"2020-12-30T14:31:53+00:00\",\"dateModified\":\"2023-02-27T11:08:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/\"},\"wordCount\":859,\"publisher\":{\"@id\":\"https:\/\/mms-seminar.com\/it\/#organization\"},\"image\":{\"@id\":\"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2015\/06\/DirkSchrader.jpg\",\"articleSection\":[\"MMS-Blog\",\"Non categorizzato\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/\",\"url\":\"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/\",\"name\":\"Incurabile era ieri! - MMS Seminar | Chlordioxid (CDS\/CDL) nach Jim Humble &amp; A. Kalcker\",\"isPartOf\":{\"@id\":\"https:\/\/mms-seminar.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2015\/06\/DirkSchrader.jpg\",\"datePublished\":\"2020-12-30T14:31:53+00:00\",\"dateModified\":\"2023-02-27T11:08:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/#primaryimage\",\"url\":\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2015\/06\/DirkSchrader.jpg\",\"contentUrl\":\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2015\/06\/DirkSchrader.jpg\",\"width\":282,\"height\":304},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mms-seminar.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Incurabile era ieri!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mms-seminar.com\/it\/#website\",\"url\":\"https:\/\/mms-seminar.com\/it\/\",\"name\":\"MMS Seminar | Chlordioxid (CDS\/CDL) nach Jim Humble & A. Kalcker\",\"description\":\"Dein Wissensportal zu MMS, CDS\/CDL &amp; Methylenblau nach Jim Humble und Andreas Kalcker.\",\"publisher\":{\"@id\":\"https:\/\/mms-seminar.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mms-seminar.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mms-seminar.com\/it\/#organization\",\"name\":\"MMS-Seminar\",\"url\":\"https:\/\/mms-seminar.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/mms-seminar.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2017\/08\/cropped-mms-logo-weiss-560x80-2.png\",\"contentUrl\":\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2017\/08\/cropped-mms-logo-weiss-560x80-2.png\",\"width\":446,\"height\":80,\"caption\":\"MMS-Seminar\"},\"image\":{\"@id\":\"https:\/\/mms-seminar.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/MMSseminare\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/mms-seminar.com\/it\/#\/schema\/person\/12cfbf6bc9c92529d726b3c9281772bd\",\"name\":\"Teamer MMSler\",\"url\":\"https:\/\/mms-seminar.com\/it\/author\/mms-dreamteam2016-2-2-2-2-2-2\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Incurabile era ieri! - MMS Seminar | Chlordioxid (CDS\/CDL) nach Jim Humble &amp; A. Kalcker","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/","og_locale":"it_IT","og_type":"article","og_title":"Incurabile era ieri!","og_description":"Dal veterinario di Amburgo Dirk Schrader: &#8220;\u00c8 il destino toccante di diversi cani e di un puledro che mi fa pensare se l&#8217;insegnamento delle infezioni in medicina veterinaria debba essere riscritto. Somministrare una sostanza di mia produzione, [&hellip;]","og_url":"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/","og_site_name":"MMS Seminar | Chlordioxid (CDS\/CDL) nach Jim Humble &amp; A. Kalcker","article_publisher":"https:\/\/www.facebook.com\/MMSseminare","article_published_time":"2020-12-30T14:31:53+00:00","article_modified_time":"2023-02-27T11:08:09+00:00","og_image":[{"width":282,"height":304,"url":"https:\/\/mms-seminar.com\/wp-content\/uploads\/2015\/06\/DirkSchrader.jpg","type":"image\/jpeg"}],"author":"Teamer MMSler","twitter_misc":{"Scritto da":"Teamer MMSler","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/#article","isPartOf":{"@id":"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/"},"author":{"name":"Teamer MMSler","@id":"https:\/\/mms-seminar.com\/it\/#\/schema\/person\/12cfbf6bc9c92529d726b3c9281772bd"},"headline":"Incurabile era ieri!","datePublished":"2020-12-30T14:31:53+00:00","dateModified":"2023-02-27T11:08:09+00:00","mainEntityOfPage":{"@id":"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/"},"wordCount":859,"publisher":{"@id":"https:\/\/mms-seminar.com\/it\/#organization"},"image":{"@id":"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/#primaryimage"},"thumbnailUrl":"https:\/\/mms-seminar.com\/wp-content\/uploads\/2015\/06\/DirkSchrader.jpg","articleSection":["MMS-Blog","Non categorizzato"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/","url":"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/","name":"Incurabile era ieri! - MMS Seminar | Chlordioxid (CDS\/CDL) nach Jim Humble &amp; A. Kalcker","isPartOf":{"@id":"https:\/\/mms-seminar.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/#primaryimage"},"image":{"@id":"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/#primaryimage"},"thumbnailUrl":"https:\/\/mms-seminar.com\/wp-content\/uploads\/2015\/06\/DirkSchrader.jpg","datePublished":"2020-12-30T14:31:53+00:00","dateModified":"2023-02-27T11:08:09+00:00","breadcrumb":{"@id":"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/#primaryimage","url":"https:\/\/mms-seminar.com\/wp-content\/uploads\/2015\/06\/DirkSchrader.jpg","contentUrl":"https:\/\/mms-seminar.com\/wp-content\/uploads\/2015\/06\/DirkSchrader.jpg","width":282,"height":304},{"@type":"BreadcrumbList","@id":"https:\/\/mms-seminar.com\/it\/incurabile-era-ieri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mms-seminar.com\/it\/"},{"@type":"ListItem","position":2,"name":"Incurabile era ieri!"}]},{"@type":"WebSite","@id":"https:\/\/mms-seminar.com\/it\/#website","url":"https:\/\/mms-seminar.com\/it\/","name":"MMS Seminar | Chlordioxid (CDS\/CDL) nach Jim Humble & A. Kalcker","description":"Dein Wissensportal zu MMS, CDS\/CDL &amp; Methylenblau nach Jim Humble und Andreas Kalcker.","publisher":{"@id":"https:\/\/mms-seminar.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mms-seminar.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/mms-seminar.com\/it\/#organization","name":"MMS-Seminar","url":"https:\/\/mms-seminar.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mms-seminar.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/mms-seminar.com\/wp-content\/uploads\/2017\/08\/cropped-mms-logo-weiss-560x80-2.png","contentUrl":"https:\/\/mms-seminar.com\/wp-content\/uploads\/2017\/08\/cropped-mms-logo-weiss-560x80-2.png","width":446,"height":80,"caption":"MMS-Seminar"},"image":{"@id":"https:\/\/mms-seminar.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MMSseminare"]},{"@type":"Person","@id":"https:\/\/mms-seminar.com\/it\/#\/schema\/person\/12cfbf6bc9c92529d726b3c9281772bd","name":"Teamer MMSler","url":"https:\/\/mms-seminar.com\/it\/author\/mms-dreamteam2016-2-2-2-2-2-2\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/mms-seminar.com\/wp-content\/uploads\/2015\/06\/DirkSchrader.jpg",282,304,false],"thumbnail":["https:\/\/mms-seminar.com\/wp-content\/uploads\/2015\/06\/DirkSchrader-150x150.jpg",150,150,true],"medium":["https:\/\/mms-seminar.com\/wp-content\/uploads\/2015\/06\/DirkSchrader-278x300.jpg",278,300,true],"medium_large":["https:\/\/mms-seminar.com\/wp-content\/uploads\/2015\/06\/DirkSchrader.jpg",282,304,false],"large":["https:\/\/mms-seminar.com\/wp-content\/uploads\/2015\/06\/DirkSchrader.jpg",282,304,false],"1536x1536":["https:\/\/mms-seminar.com\/wp-content\/uploads\/2015\/06\/DirkSchrader.jpg",282,304,false],"2048x2048":["https:\/\/mms-seminar.com\/wp-content\/uploads\/2015\/06\/DirkSchrader.jpg",282,304,false]},"uagb_author_info":{"display_name":"Teamer MMSler","author_link":"https:\/\/mms-seminar.com\/it\/author\/mms-dreamteam2016-2-2-2-2-2-2\/"},"uagb_comment_info":0,"uagb_excerpt":"Dal veterinario di Amburgo Dirk Schrader: &#8220;\u00c8 il destino toccante di diversi cani e di un puledro che mi fa pensare se l&#8217;insegnamento delle infezioni in medicina veterinaria debba essere riscritto. Somministrare una sostanza di mia produzione, [&hellip;]","_links":{"self":[{"href":"https:\/\/mms-seminar.com\/it\/wp-json\/wp\/v2\/posts\/37173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mms-seminar.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mms-seminar.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mms-seminar.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mms-seminar.com\/it\/wp-json\/wp\/v2\/comments?post=37173"}],"version-history":[{"count":0,"href":"https:\/\/mms-seminar.com\/it\/wp-json\/wp\/v2\/posts\/37173\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mms-seminar.com\/it\/wp-json\/wp\/v2\/media\/37014"}],"wp:attachment":[{"href":"https:\/\/mms-seminar.com\/it\/wp-json\/wp\/v2\/media?parent=37173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mms-seminar.com\/it\/wp-json\/wp\/v2\/categories?post=37173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mms-seminar.com\/it\/wp-json\/wp\/v2\/tags?post=37173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}