{"id":33495,"date":"2020-12-29T17:45:24","date_gmt":"2020-12-29T16:45:24","guid":{"rendered":"https:\/\/mms-seminar.com\/falso-o-real-cloroquina-una-panacea\/"},"modified":"2023-02-27T11:59:09","modified_gmt":"2023-02-27T10:59:09","slug":"falso-o-real-cloroquina-una-panacea","status":"publish","type":"post","link":"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/","title":{"rendered":"Falso o real: Cloroquina, \u00bfuna panacea?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"33495\" class=\"elementor elementor-33495 elementor-29808\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-46dca69 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"46dca69\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0c003aa\" data-id=\"0c003aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1222ecb elementor-widget elementor-widget-heading\" data-id=\"1222ecb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Falso o real: Cloroquina, \u00bfuna panacea?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-97f898d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"97f898d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4f8d37b\" data-id=\"4f8d37b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15037f9 elementor-widget elementor-widget-text-editor\" data-id=\"15037f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"title style-scope ytd-video-primary-info-renderer\"><strong>\u00bfEs la cloroquina (hidroxicloroquina &#8211; nombre comercial Resochin)<\/strong>, la panacea que la humanidad ha estado esperando? Despu\u00e9s de que Donald Trump y Emmanuel Macron informaron positivamente sobre ello, la demanda ha aumentado en todo el mundo. \u00bfCumple su promesa o debemos ser prudentes y observar los acontecimientos con un ojo cauteloso?<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8590a5b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8590a5b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-603ca9e\" data-id=\"603ca9e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7eef48 elementor-widget elementor-widget-video\" data-id=\"a7eef48\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe\" allowfullscreen allow=\"clipboard-write\" title=\"Reproductor de v\u00eddeo vimeo\" src=\"https:\/\/player.vimeo.com\/video\/421480881?color&amp;autopause=0&amp;loop=0&amp;muted=0&amp;title=1&amp;portrait=1&amp;byline=1#t=\"><\/iframe>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-553847ab elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"553847ab\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-65d82dc5\" data-id=\"65d82dc5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1d2ba14c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1d2ba14c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7955f78c\" data-id=\"7955f78c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b34f10a elementor-widget elementor-widget-spacer\" data-id=\"3b34f10a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5150046 elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"5150046\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ticketshop.akasha-congress.com.\/s\/AKASHA-Congress?group_id=816\" target=\"_blank\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"400\" src=\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/06\/Banner_quer_mms-dvd.jpg\" class=\"attachment-full size-full wp-image-33343\" alt=\"\" srcset=\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/06\/Banner_quer_mms-dvd.jpg 1200w, https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/06\/Banner_quer_mms-dvd-300x100.jpg 300w, https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/06\/Banner_quer_mms-dvd-1024x341.jpg 1024w, https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/06\/Banner_quer_mms-dvd-768x256.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-49f92984 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"49f92984\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-778782ce\" data-id=\"778782ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1bb8d05d elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"1bb8d05d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ticketshop.akasha-congress.com.\/s\/AKASHA-Congress?group_id=816\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"250\" src=\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/06\/Banner_mobile_video.gif\" class=\"attachment-full size-full wp-image-33346\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14e80589 elementor-widget elementor-widget-spacer\" data-id=\"14e80589\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2136c1b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2136c1b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ad21d0b\" data-id=\"ad21d0b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b6286c elementor-widget elementor-widget-text-editor\" data-id=\"9b6286c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Seg\u00fan el presidente de los EE.UU., es \u00abmuy posible\u00bb que el medicamento contra la malaria act\u00fae como protecci\u00f3n contra el Covid-19. Adem\u00e1s, muchos militares la habr\u00edan tomado diariamente durante a\u00f1os. \u00bfEs una cura milagrosa despu\u00e9s de todo?<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-623cd3d elementor-widget elementor-widget-video\" data-id=\"623cd3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=CsV5K8D6Efw&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c3b41f0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c3b41f0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ef315df\" data-id=\"ef315df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-acc47ab elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"acc47ab\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cad5b29\" data-id=\"cad5b29\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13bd2b3 elementor-widget elementor-widget-heading\" data-id=\"13bd2b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Actualizaci\u00f3n:<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3c59b16 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c59b16\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-48ae28c\" data-id=\"48ae28c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a15de1a elementor-widget elementor-widget-text-editor\" data-id=\"a15de1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Se nos hizo saber que la cloroquina y la hidroxicloroquina son qu\u00edmicamente similares, pero no son lo mismo. Sin embargo, en Wikipedia se habla de las \u00e1reas de aplicaci\u00f3n y los efectos secundarios de una manera muy variada. \u00bfQui\u00e9n puede aclarar esto?<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b57d005 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b57d005\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c39ef60\" data-id=\"c39ef60\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-02f572e elementor-widget elementor-widget-video\" data-id=\"02f572e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe\" allowfullscreen allow=\"clipboard-write\" title=\"Reproductor de v\u00eddeo vimeo\" src=\"https:\/\/player.vimeo.com\/video\/424955997?color&amp;autopause=0&amp;loop=0&amp;muted=0&amp;title=1&amp;portrait=1&amp;byline=1#t=\"><\/iframe>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23bb8b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"23bb8b9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-39e23f7\" data-id=\"39e23f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-03d5ac3 elementor-widget elementor-widget-text-editor\" data-id=\"03d5ac3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El <strong>Dr. Wolfgang Wodarg<\/strong> dice: La hidroxicloroquina con una prueba positiva de SARS-CoV-2 es <strong>potencialmente mortal para las personas con deficiencia de G6PD<\/strong>.<\/p>\n<p>La hidroxicloroquina (HCQ) es un antiguo medicamento antipal\u00fadico. Se han notificado efectos secundarios card\u00edacos y oftalmol\u00f3gicos graves. El HCQ no est\u00e1 aprobado para el Covid-19. Sin embargo, se ha utilizado en Italia y sigue utiliz\u00e1ndose en muchos pa\u00edses con un uso compasivo. Dado que no s\u00f3lo la alarma del virus sino tambi\u00e9n el mensaje sobre un posible beneficio del HCQ para combatirlo se propag\u00f3 desde Wuhan, ha habido muchos malos estudios sobre esto. Se dice que otros 140 estudios m\u00e1s o menos que usan HCQ ya est\u00e1n registrados.<\/p>\n<p>El HCQ se ha utilizado incluso en personas completamente sanas \u00abpara prevenir cursos severos\u00bb y profil\u00e1cticamente para el personal m\u00e9dico. La dosis recomendada es aproximadamente 20 veces la de la profilaxis de la malaria (400-800mg por d\u00eda). En la actualidad se est\u00e1 intensificando el uso e incluso se est\u00e1n construyendo nuevas instalaciones de producci\u00f3n (por ejemplo, en el Camer\u00fan y la India) de HCQ. Todo esto se hace sin pruebas suficientes de un efecto cl\u00ednico beneficioso de la HCQ en los casos positivos de SARS-CoV-2, y mucho menos en los casos negativos.<\/p>\n<p>Sin embargo, hace mucho tiempo que se identific\u00f3 a la HCQ como una de las drogas que causan da\u00f1os graves, por ejemplo a los eritrocitos, en personas con deficiencia hereditaria de glucosa-6-fosfato deshidrogenasa (G6PD). Como efecto de la aplicaci\u00f3n de HCQ en la deficiencia de G6DP, se observa una hem\u00f3lisis severa despu\u00e9s de 1-2 d\u00edas. Los restos de eritrocitos causan microembolios y da\u00f1an \u00f3rganos delicados como los ri\u00f1ones y el cerebro. Adem\u00e1s, faltan los eritrocitos como portadores de ox\u00edgeno. 1-2 d\u00edas despu\u00e9s del comienzo de dicho tratamiento se desarrolla un cuadro cl\u00ednico muy severo con debilidad, mareos, falta de aliento y signos de da\u00f1o en los \u00f3rganos. Esto puede terminar en la muerte si la medicaci\u00f3n t\u00f3xica no se suspende inmediatamente.<br \/>Cuando se suspende la droga, la falta de aliento mejora espont\u00e1neamente gracias a una r\u00e1pida normalizaci\u00f3n del recuento sangu\u00edneo. Por encima de todo, sigue siendo importante controlar la funci\u00f3n renal.<\/p>\n<p>La medicaci\u00f3n HCQ podr\u00eda ser una raz\u00f3n para los casos en los que -como en los EE.UU.- se observaba frecuentemente una grave falta de aliento sin los t\u00edpicos signos de neumon\u00eda. \u00bfHab\u00edan recibido los pacientes recientemente HCQ? Los afroamericanos representan el 6 por ciento de la poblaci\u00f3n de los Estados Unidos, pero casi el 40 por ciento de las muertes de Covid 19 (5). \u00bfAlguien ha investigado si los pacientes podr\u00edan tener una deficiencia de G6PD? No hay debate sobre eso. Esta posibilidad ni siquiera se considera en los estudios. Los servicios de salud italianos y australianos han advertido finalmente contra el uso de HCQ en la deficiencia de G6PD.<\/p>\n<p>Casi nadie parece ser consciente de que en el \u00c1frica subsahariana, por ejemplo, la deficiencia hereditaria de G6PD est\u00e1 muy extendida (20-30% de la poblaci\u00f3n). Sin embargo, tambi\u00e9n hay una alta prevalencia de la deficiencia de la G6PD en otros pa\u00edses en los que el paludismo era o sigue siendo end\u00e9mico. La deficiencia de G6PD tambi\u00e9n debe considerarse en las familias de inmigrantes, como las de Chicago, Nueva York y otros lugares. En estas poblaciones, desencadenadas por los ya cuestionables resultados de las pruebas de SARS-CoV-2, el tratamiento o la prevenci\u00f3n con drogas peligrosas como el HCQ por s\u00ed solo puede matar a muchas personas. Les recuerdo estas conexiones porque muchos de los nuevos estudios de HCQ no excluyen espec\u00edficamente a los sujetos con esta deficiencia enzim\u00e1tica.<\/p>\n<p>No hay conflictos de intereses<br \/>23 de abril de 2020<br \/>Dr. Wolfgang Wodarg<br \/>Medicina interna-neumolog\u00eda, higiene y medicina ambiental<br \/>el Jueves, 23 Abril 2020, 14:37<br \/>P\u00e1gina web: <a style=\"font-size: 16px; background-color: #ffffff;\" href=\"https:\/\/www.wodarg.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.wodarg.com\/<\/a><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58f62ec elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58f62ec\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7050673a\" data-id=\"7050673a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b4e6bbe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b4e6bbe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-adce612\" data-id=\"adce612\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc76af9 elementor-widget elementor-widget-spacer\" data-id=\"cc76af9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-541a0ec3 elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"541a0ec3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/aquarius-prolife.com\/de\/30-mms-water-filter\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1200\" height=\"400\" src=\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/Banner_quer_wasserfilter.jpg\" class=\"attachment-full size-full wp-image-33293\" alt=\"\" srcset=\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/Banner_quer_wasserfilter.jpg 1200w, https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/Banner_quer_wasserfilter-300x100.jpg 300w, https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/Banner_quer_wasserfilter-1024x341.jpg 1024w, https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/Banner_quer_wasserfilter-768x256.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-49a5f4c6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"49a5f4c6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-44fb93cc\" data-id=\"44fb93cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69a40f53 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"69a40f53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/aquarius-prolife.com\/de\/30-mms-water-filter\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"250\" src=\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/06\/Banner_mobile_wasserfilter.gif\" class=\"attachment-full size-full wp-image-33296\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-334f6415 elementor-widget elementor-widget-spacer\" data-id=\"334f6415\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Falso o real: Cloroquina, \u00bfuna panacea? \u00bfEs la cloroquina (hidroxicloroquina &#8211; nombre comercial Resochin), la panacea que la humanidad ha estado esperando? Despu\u00e9s de que Donald Trump y Emmanuel Macron informaron positivamente sobre ello, la demanda ha [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33508,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1262,983],"tags":[],"class_list":["post-33495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mms-blog","category-sin-categorizar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Falso o real: Cloroquina, \u00bfuna panacea?<\/title>\n<meta name=\"description\" content=\"\u00bfEs la cloroquina (hidroxicloroquina - nombre comercial Resochin), la panacea que la humanidad ha estado esperando?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Falso o real: Cloroquina, \u00bfuna panacea?\" \/>\n<meta property=\"og:description\" content=\"\u00bfEs la cloroquina (hidroxicloroquina - nombre comercial Resochin), la panacea que la humanidad ha estado esperando?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/\" \/>\n<meta property=\"og:site_name\" content=\"MMS Seminar | Chlordioxid (CDS\/CDL) nach Jim Humble &amp; A. Kalcker\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MMSseminare\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-29T16:45:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-27T10:59:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/226-Fakten-oder-Fake-Vesna-Ali.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1668\" \/>\n\t<meta property=\"og:image:height\" content=\"936\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Teamer MMSler\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Teamer MMSler\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/\"},\"author\":{\"name\":\"Teamer MMSler\",\"@id\":\"https:\/\/mms-seminar.com\/es\/#\/schema\/person\/12cfbf6bc9c92529d726b3c9281772bd\"},\"headline\":\"Falso o real: Cloroquina, \u00bfuna panacea?\",\"datePublished\":\"2020-12-29T16:45:24+00:00\",\"dateModified\":\"2023-02-27T10:59:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/\"},\"wordCount\":847,\"publisher\":{\"@id\":\"https:\/\/mms-seminar.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/226-Fakten-oder-Fake-Vesna-Ali.jpg\",\"articleSection\":[\"MMS-Blog\",\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/\",\"url\":\"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/\",\"name\":\"Falso o real: Cloroquina, \u00bfuna panacea?\",\"isPartOf\":{\"@id\":\"https:\/\/mms-seminar.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/226-Fakten-oder-Fake-Vesna-Ali.jpg\",\"datePublished\":\"2020-12-29T16:45:24+00:00\",\"dateModified\":\"2023-02-27T10:59:09+00:00\",\"description\":\"\u00bfEs la cloroquina (hidroxicloroquina - nombre comercial Resochin), la panacea que la humanidad ha estado esperando?\",\"breadcrumb\":{\"@id\":\"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/#primaryimage\",\"url\":\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/226-Fakten-oder-Fake-Vesna-Ali.jpg\",\"contentUrl\":\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/226-Fakten-oder-Fake-Vesna-Ali.jpg\",\"width\":1668,\"height\":936},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mms-seminar.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Falso o real: Cloroquina, \u00bfuna panacea?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mms-seminar.com\/es\/#website\",\"url\":\"https:\/\/mms-seminar.com\/es\/\",\"name\":\"MMS Seminar | Chlordioxid (CDS\/CDL) nach Jim Humble & A. Kalcker\",\"description\":\"Dein Wissensportal zu MMS, CDS\/CDL &amp; Methylenblau nach Jim Humble und Andreas Kalcker.\",\"publisher\":{\"@id\":\"https:\/\/mms-seminar.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mms-seminar.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mms-seminar.com\/es\/#organization\",\"name\":\"MMS-Seminar\",\"url\":\"https:\/\/mms-seminar.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/mms-seminar.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2017\/08\/cropped-mms-logo-weiss-560x80-2.png\",\"contentUrl\":\"https:\/\/mms-seminar.com\/wp-content\/uploads\/2017\/08\/cropped-mms-logo-weiss-560x80-2.png\",\"width\":446,\"height\":80,\"caption\":\"MMS-Seminar\"},\"image\":{\"@id\":\"https:\/\/mms-seminar.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/MMSseminare\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/mms-seminar.com\/es\/#\/schema\/person\/12cfbf6bc9c92529d726b3c9281772bd\",\"name\":\"Teamer MMSler\",\"url\":\"https:\/\/mms-seminar.com\/es\/author\/mms-dreamteam2016-2-2-2-2-2-2\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Falso o real: Cloroquina, \u00bfuna panacea?","description":"\u00bfEs la cloroquina (hidroxicloroquina - nombre comercial Resochin), la panacea que la humanidad ha estado esperando?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/","og_locale":"es_ES","og_type":"article","og_title":"Falso o real: Cloroquina, \u00bfuna panacea?","og_description":"\u00bfEs la cloroquina (hidroxicloroquina - nombre comercial Resochin), la panacea que la humanidad ha estado esperando?","og_url":"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/","og_site_name":"MMS Seminar | Chlordioxid (CDS\/CDL) nach Jim Humble &amp; A. Kalcker","article_publisher":"https:\/\/www.facebook.com\/MMSseminare","article_published_time":"2020-12-29T16:45:24+00:00","article_modified_time":"2023-02-27T10:59:09+00:00","og_image":[{"width":1668,"height":936,"url":"https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/226-Fakten-oder-Fake-Vesna-Ali.jpg","type":"image\/jpeg"}],"author":"Teamer MMSler","twitter_misc":{"Escrito por":"Teamer MMSler","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/#article","isPartOf":{"@id":"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/"},"author":{"name":"Teamer MMSler","@id":"https:\/\/mms-seminar.com\/es\/#\/schema\/person\/12cfbf6bc9c92529d726b3c9281772bd"},"headline":"Falso o real: Cloroquina, \u00bfuna panacea?","datePublished":"2020-12-29T16:45:24+00:00","dateModified":"2023-02-27T10:59:09+00:00","mainEntityOfPage":{"@id":"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/"},"wordCount":847,"publisher":{"@id":"https:\/\/mms-seminar.com\/es\/#organization"},"image":{"@id":"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/#primaryimage"},"thumbnailUrl":"https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/226-Fakten-oder-Fake-Vesna-Ali.jpg","articleSection":["MMS-Blog","Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/","url":"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/","name":"Falso o real: Cloroquina, \u00bfuna panacea?","isPartOf":{"@id":"https:\/\/mms-seminar.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/#primaryimage"},"image":{"@id":"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/#primaryimage"},"thumbnailUrl":"https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/226-Fakten-oder-Fake-Vesna-Ali.jpg","datePublished":"2020-12-29T16:45:24+00:00","dateModified":"2023-02-27T10:59:09+00:00","description":"\u00bfEs la cloroquina (hidroxicloroquina - nombre comercial Resochin), la panacea que la humanidad ha estado esperando?","breadcrumb":{"@id":"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/#primaryimage","url":"https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/226-Fakten-oder-Fake-Vesna-Ali.jpg","contentUrl":"https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/226-Fakten-oder-Fake-Vesna-Ali.jpg","width":1668,"height":936},{"@type":"BreadcrumbList","@id":"https:\/\/mms-seminar.com\/es\/falso-o-real-cloroquina-una-panacea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mms-seminar.com\/es\/"},{"@type":"ListItem","position":2,"name":"Falso o real: Cloroquina, \u00bfuna panacea?"}]},{"@type":"WebSite","@id":"https:\/\/mms-seminar.com\/es\/#website","url":"https:\/\/mms-seminar.com\/es\/","name":"MMS Seminar | Chlordioxid (CDS\/CDL) nach Jim Humble & A. Kalcker","description":"Dein Wissensportal zu MMS, CDS\/CDL &amp; Methylenblau nach Jim Humble und Andreas Kalcker.","publisher":{"@id":"https:\/\/mms-seminar.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mms-seminar.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mms-seminar.com\/es\/#organization","name":"MMS-Seminar","url":"https:\/\/mms-seminar.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mms-seminar.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/mms-seminar.com\/wp-content\/uploads\/2017\/08\/cropped-mms-logo-weiss-560x80-2.png","contentUrl":"https:\/\/mms-seminar.com\/wp-content\/uploads\/2017\/08\/cropped-mms-logo-weiss-560x80-2.png","width":446,"height":80,"caption":"MMS-Seminar"},"image":{"@id":"https:\/\/mms-seminar.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MMSseminare"]},{"@type":"Person","@id":"https:\/\/mms-seminar.com\/es\/#\/schema\/person\/12cfbf6bc9c92529d726b3c9281772bd","name":"Teamer MMSler","url":"https:\/\/mms-seminar.com\/es\/author\/mms-dreamteam2016-2-2-2-2-2-2\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/226-Fakten-oder-Fake-Vesna-Ali.jpg",1668,936,false],"thumbnail":["https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/226-Fakten-oder-Fake-Vesna-Ali-150x150.jpg",150,150,true],"medium":["https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/226-Fakten-oder-Fake-Vesna-Ali-300x168.jpg",300,168,true],"medium_large":["https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/226-Fakten-oder-Fake-Vesna-Ali-768x431.jpg",768,431,true],"large":["https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/226-Fakten-oder-Fake-Vesna-Ali-1024x575.jpg",1024,575,true],"1536x1536":["https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/226-Fakten-oder-Fake-Vesna-Ali-1536x862.jpg",1536,862,true],"2048x2048":["https:\/\/mms-seminar.com\/wp-content\/uploads\/2020\/05\/226-Fakten-oder-Fake-Vesna-Ali.jpg",1668,936,false]},"uagb_author_info":{"display_name":"Teamer MMSler","author_link":"https:\/\/mms-seminar.com\/es\/author\/mms-dreamteam2016-2-2-2-2-2-2\/"},"uagb_comment_info":0,"uagb_excerpt":"Falso o real: Cloroquina, \u00bfuna panacea? \u00bfEs la cloroquina (hidroxicloroquina &#8211; nombre comercial Resochin), la panacea que la humanidad ha estado esperando? Despu\u00e9s de que Donald Trump y Emmanuel Macron informaron positivamente sobre ello, la demanda ha [&hellip;]","_links":{"self":[{"href":"https:\/\/mms-seminar.com\/es\/wp-json\/wp\/v2\/posts\/33495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mms-seminar.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mms-seminar.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mms-seminar.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mms-seminar.com\/es\/wp-json\/wp\/v2\/comments?post=33495"}],"version-history":[{"count":0,"href":"https:\/\/mms-seminar.com\/es\/wp-json\/wp\/v2\/posts\/33495\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mms-seminar.com\/es\/wp-json\/wp\/v2\/media\/33508"}],"wp:attachment":[{"href":"https:\/\/mms-seminar.com\/es\/wp-json\/wp\/v2\/media?parent=33495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mms-seminar.com\/es\/wp-json\/wp\/v2\/categories?post=33495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mms-seminar.com\/es\/wp-json\/wp\/v2\/tags?post=33495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}